{"id":2503,"date":"2023-08-30T17:58:56","date_gmt":"2023-08-30T15:58:56","guid":{"rendered":"https:\/\/halawedd.com\/?post_type=portfolio&#038;p=2503"},"modified":"2023-10-15T18:31:12","modified_gmt":"2023-10-15T16:31:12","slug":"yurii-lera","status":"publish","type":"portfolio","link":"https:\/\/halawedd.com\/de\/portfolio-project\/yurii-lera\/","title":{"rendered":"Jurij und Lera"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"<p>Yurii &amp; Lera in der Schweiz. Inmitten der goldenen Wellen eines sonnenverw\u00f6hnten Weizenfeldes findet ein \u00e4sthetisches Fotoshooting von Liebenden statt. Das Paar ist in eine vertr\u00e4umte Landschaft eingetaucht, in der die sanfte Brise wie das Fl\u00fcstern der Natur durch die Felder streicht. In sanften Pastellfarben gekleidet k\u00fcssen sie sich heimlich, wobei ihre Liebe einen sch\u00f6nen Kontrast zur l\u00e4ndlichen Landschaft bildet. Das warme, bernsteinfarbene Licht der untergehenden Sonne taucht sie in ein sanftes Leuchten und erhellt ihr Lachen und ihre Intimit\u00e4t. Die ruhige Sch\u00f6nheit des Feldes und die Verbundenheit des Paares vereinen sich zu einem zeitlosen Tableau, das die Harmonie zwischen ihrer Liebe und der heiteren, nat\u00fcrlichen Welt, die sie umgibt, feiert.<\/p>","protected":false},"featured_media":2504,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","project-cat":[8],"class_list":["post-2503","portfolio","type-portfolio","status-publish","has-post-thumbnail","hentry","project-cat-couples"],"acf":[],"_links":{"self":[{"href":"https:\/\/halawedd.com\/de\/wp-json\/wp\/v2\/portfolio\/2503","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/halawedd.com\/de\/wp-json\/wp\/v2\/portfolio"}],"about":[{"href":"https:\/\/halawedd.com\/de\/wp-json\/wp\/v2\/types\/portfolio"}],"replies":[{"embeddable":true,"href":"https:\/\/halawedd.com\/de\/wp-json\/wp\/v2\/comments?post=2503"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/halawedd.com\/de\/wp-json\/wp\/v2\/media\/2504"}],"wp:attachment":[{"href":"https:\/\/halawedd.com\/de\/wp-json\/wp\/v2\/media?parent=2503"}],"wp:term":[{"taxonomy":"project-cat","embeddable":true,"href":"https:\/\/halawedd.com\/de\/wp-json\/wp\/v2\/project-cat?post=2503"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}